{"id":29708,"date":"2025-04-18T08:20:53","date_gmt":"2025-04-18T08:20:53","guid":{"rendered":"https:\/\/vroteina.com\/?post_type=product&#038;p=29708"},"modified":"2026-06-07T12:17:39","modified_gmt":"2026-06-07T12:17:39","slug":"vitamina-b12-en-spray","status":"publish","type":"product","link":"https:\/\/vroteina.com\/pt\/product\/vitamina-b12-en-spray\/","title":{"rendered":"SPRAY DE VITAMINA B12"},"content":{"rendered":"<div class=\"row\">\n<div class=\"product-content entry-content\">\n<div id=\"vc_row-67f388c2d8b59\" class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n<figure class=\"wpb_wrapper vc_figure\">\n<div class=\"vc_tta-container woocommerce-tabs wc-tabs-wrapper gem-woocommerce-tabs\" data-vc-action=\"collapse\">\n<div class=\"vc_general vc_tta vc_tta-tabs vc_tta-color-thegem vc_tta-style-classic vc_tta-shape-square vc_tta-spacing-5 vc_tta-tabs-position-top vc_tta-controls-align-left\">\n<div class=\"vc_tta-panels-container\">\n<div class=\"vc_tta-panels\">\n<div id=\"tab-description\" class=\"vc_tta-panel vc_active\" data-vc-content=\".vc_tta-panel-body\">\n<div class=\"vc_tta-panel-body\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span class=\"light\"><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">Vitamina B12<\/span><\/span><\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<p>Suplemento alimentar l\u00edquido pronto a usar<br \/>\na base de vitamina B12.<\/p>\n<p>Spray l\u00edquido<br \/>\n175 doses de 0,28 ml<br \/>\nQuantidade l\u00edquida: 50 ml<\/p>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">A vitamina B12 contribui para o metabolismo energ\u00e9tico normal.<\/div>\n<div class=\"wpb_wrapper\">A vitamina B12 contribui para o funcionamento normal do sistema nervoso.<\/div>\n<div class=\"wpb_wrapper\">A vitamina B12 contribui para o metabolismo normal da homociste\u00edna.<\/div>\n<div class=\"wpb_wrapper\">A vitamina B12 contribui para a fun\u00e7\u00e3o psicol\u00f3gica normal.<\/div>\n<div class=\"wpb_wrapper\">A vitamina B12 contribui para a forma\u00e7\u00e3o normal de gl\u00f3bulos vermelhos.<\/div>\n<div class=\"wpb_wrapper\">A vitamina B12 contribui para o normal funcionamento do sistema imunit\u00e1rio.<\/div>\n<div class=\"wpb_wrapper\">A vitamina B12 ajuda a diminuir o cansa\u00e7o e a fadiga.<\/div>\n<div class=\"wpb_wrapper\">A vitamina B12 contribui para o processo de divis\u00e3o celular<\/div>\n<\/div>\n<div class=\"vc_tta-container woocommerce-tabs wc-tabs-wrapper gem-woocommerce-tabs\" data-vc-action=\"collapse\">\n<div class=\"vc_general vc_tta vc_tta-tabs vc_tta-color-thegem vc_tta-style-classic vc_tta-shape-square vc_tta-spacing-5 vc_tta-tabs-position-top vc_tta-controls-align-left\">\n<div class=\"vc_tta-panels-container\">\n<div class=\"vc_tta-panels\">\n<div id=\"tab-description\" class=\"vc_tta-panel vc_active\" data-vc-content=\".vc_tta-panel-body\">\n<div class=\"vc_tta-panel-body\">\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-30645 size-full\" src=\"https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-1.png\" alt=\"\" width=\"684\" height=\"609\" srcset=\"https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-1.png 684w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-1-300x267.png 300w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-1-13x12.png 13w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-1-600x534.png 600w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/><\/p>\n<div class=\"vc_tta-container woocommerce-tabs wc-tabs-wrapper gem-woocommerce-tabs\" data-vc-action=\"collapse\">\n<div class=\"vc_general vc_tta vc_tta-tabs vc_tta-color-thegem vc_tta-style-classic vc_tta-shape-square vc_tta-spacing-5 vc_tta-tabs-position-top vc_tta-controls-align-left\">\n<div class=\"vc_tta-panels-container\">\n<div class=\"vc_tta-panels\">\n<div id=\"tab-description\" class=\"vc_tta-panel vc_active\" data-vc-content=\".vc_tta-panel-body\">\n<div class=\"vc_tta-panel-body\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\"><img decoding=\"async\" class=\"alignnone wp-image-30651 size-large\" src=\"https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-6-1024x468.png\" alt=\"\" width=\"800\" height=\"366\" srcset=\"https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-6-1024x468.png 1024w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-6-300x137.png 300w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-6-768x351.png 768w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-6-18x8.png 18w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-6-600x274.png 600w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-6.png 1125w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<h5><\/h5>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"product-content entry-content\">\n<div id=\"vc_row-680a7063a5964\" class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"title-h3\"><span class=\"light\"><span class=\"letter-spacing\">Vitamina B12<br \/>\n<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p>Os suplementos alimentares n\u00e3o devem ser utilizados como substitutos de uma dieta equilibrada, variada e de um estilo de vida saud\u00e1vel.<\/p>\n<p>\u00c9 importante ter uma dieta variada e equilibrada e um estilo de vida <span class=\"markv28i6eoti\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\">SAUD\u00c1VEL<\/span>.<\/p>\n<p>AVISOS: N\u00c3O EXCEDER A DOSE DI\u00c1RIA RECOMENDADA. MANTER FORA DO ALCANCE DAS CRIAN\u00c7AS. CONSERVA\u00c7\u00c3O: DEPOIS DE ABERTO, CONSERVAR NUM LOCAL FRESCO E SECO.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n<figure class=\"wpb_wrapper vc_figure\"><img decoding=\"async\" class=\"alignnone wp-image-30653 size-full\" src=\"https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-8.png\" alt=\"\" width=\"675\" height=\"492\" srcset=\"https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-8.png 675w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-8-300x219.png 300w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-8-16x12.png 16w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-8-600x437.png 600w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/><\/figure>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<h6 class=\"title-h5\">A boa forma f\u00edsica \u00e9 o resultado de anos de treino dedicado e de uma dieta saud\u00e1vel - N\u00c3O \u00e9 o resultado da toma de um suplemento alimentar.<\/h6>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"vc_row-680a7063a9a8c\" class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n<figure class=\"wpb_wrapper vc_figure\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-30652 size-full\" src=\"https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-7.png\" alt=\"\" width=\"629\" height=\"511\" srcset=\"https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-7.png 629w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-7-300x244.png 300w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-7-15x12.png 15w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-7-600x487.png 600w\" sizes=\"(max-width: 629px) 100vw, 629px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper title-h3\"><span class=\"light\"><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">PORQU\u00ca TOMAR UM SUPLEMENTO DE VITAMINA B12?<\/span><\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"title-h5\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"styled-subtitle\"><span class=\"tlid-translation translation\" lang=\"es\"><span title=\"\">Tanto numa alimenta\u00e7\u00e3o 100% \u00e0 base de vegetais como no caso dos veganos e vegetarianos, pode ser dif\u00edcil obter vitamina B12, uma vez que muito poucas plantas cont\u00eam esta vitamina. Algumas algas, como a espirulina, cont\u00eam vitamina B12, mas trata-se de uma forma que o nosso corpo n\u00e3o consegue utilizar.<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"vc_row-680a7063abf7b\" class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<h3><span class=\"light\"><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">B12 na nutri\u00e7\u00e3o vegana<\/span><\/span><\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"vc_row-680a7063ae3b2\" class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n<figure class=\"wpb_wrapper vc_figure\"><a class=\"vc_single_image-wrapper vc_box_border_grey prettyphoto\" href=\"https:\/\/veggie-style.com\/vegan-shop\/wp-content\/uploads\/2019\/09\/vitamin-b12.jpg\" target=\"_self\" data-rel=\"prettyPhoto[rel-26018-2480336512]\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img attachment-large\" src=\"https:\/\/veggie-style.com\/vegan-shop\/wp-content\/uploads\/2019\/09\/vitamin-b12.jpg\" alt=\"\" width=\"200\" height=\"177\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"title-h3\"><span class=\"light\"><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">Usamos Metilcobalamina<\/span><\/span><\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"title-h5\">\n<div class=\"gem-divider\"><\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"styled-subtitle\">\n<p><span class=\"tlid-translation translation\" lang=\"es\"><span title=\"\">Existem 4 tipos de vitamina B12:<\/span><br \/>\n<span title=\"\">Metilcobalamina<\/span><br \/>\n<span title=\"\">Adenosilcobalamina<\/span><br \/>\n<span title=\"\">Hidroxocobalamina<\/span><br \/>\n<span title=\"\">e a forma sint\u00e9tica: cianocobalamina<\/span><br \/>\n<span class=\"\" title=\"\">N\u00f3s usamos na nossa suplementa\u00e7\u00e3o a vers\u00e3o metilcobalamina.<\/span><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"vc_row-680a7063b058d\" class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<h3><span class=\"light\"><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">Efeitos saud\u00e1veis da Vitamina B12<br \/>\n<\/span><\/span><\/span><\/h3>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"title-h5\">\n<div class=\"styled-subtitle\">\n<div class=\"title-h6\">A vitamina B12 ajuda a diminuir o cansa\u00e7o e a fadiga<\/div>\n<div class=\"title-h6\">A vitamina B12 contribui para o processo de divis\u00e3o celular<\/div>\n<div class=\"title-h6\">A vitamina B12 contribui para o metabolismo energ\u00e9tico normal<\/div>\n<div class=\"title-h6\">A vitamina B12 contribui para o funcionamento normal do sistema nervoso<\/div>\n<p><span class=\"tlid-translation translation\" lang=\"es\"><span title=\"\">\u00a0<\/span><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"vc_row-680a7063b2774\" class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n<figure class=\"wpb_wrapper vc_figure\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-30654 size-full\" src=\"https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-9.png\" alt=\"\" width=\"640\" height=\"491\" srcset=\"https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-9.png 640w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-9-300x230.png 300w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-9-16x12.png 16w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/vroteina-gold-edition-B12-9-600x460.png 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper title-h3\"><span class=\"light\"><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">COMO TOMAR<\/span><\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"title-h5\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"styled-subtitle\"><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">Formul\u00e1mos uma f\u00f3rmula di\u00e1ria.<\/span> <span class=\"\" title=\"\">Pulverize o spray uma vez por dia, 2 pulveriza\u00e7\u00f5es diretamente na boca.<\/span> <span class=\"\" title=\"\">Deixar na boca durante um par de minutos antes de engolir.<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"vc_row-680a7063b48f2\" class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"title-h5\">\n<div class=\"styled-subtitle\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"styled-subtitle\"><span class=\"tlid-translation translation\" lang=\"es\"><span title=\"\">Elabor\u00e1mos uma vers\u00e3o l\u00edquida num aerossol, pela simples raz\u00e3o de que assim asseguramos uma melhor absor\u00e7\u00e3o.<\/span>\u00a0<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_center\"><\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"title-h6\">A boa forma f\u00edsica \u00e9 o resultado de anos de treino dedicado e de uma dieta saud\u00e1vel - N\u00c3O \u00e9 o resultado da toma de um suplemento alimentar.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"vc_row-680a7063b6e6c\" class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n<figure class=\"wpb_wrapper vc_figure\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-30656 size-full\" src=\"https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/ChatGPT-Image-20-ene-2026-22_20_54.png\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/ChatGPT-Image-20-ene-2026-22_20_54.png 1024w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/ChatGPT-Image-20-ene-2026-22_20_54-300x300.png 300w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/ChatGPT-Image-20-ene-2026-22_20_54-150x150.png 150w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/ChatGPT-Image-20-ene-2026-22_20_54-768x768.png 768w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/ChatGPT-Image-20-ene-2026-22_20_54-12x12.png 12w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/ChatGPT-Image-20-ene-2026-22_20_54-600x600.png 600w, https:\/\/vroteina.com\/wp-content\/uploads\/2025\/04\/ChatGPT-Image-20-ene-2026-22_20_54-100x100.png 100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"title-h6\">A vitamina B12 contribui para o metabolismo normal da homociste\u00edna<\/div>\n<div class=\"title-h6\">A vitamina B12 contribui para a fun\u00e7\u00e3o psicol\u00f3gica normal<\/div>\n<div class=\"title-h6\">A vitamina B12 contribui para a forma\u00e7\u00e3o normal de gl\u00f3bulos vermelhos<\/div>\n<div class=\"title-h6\">A vitamina B12 contribui para o funcionamento normal do sistema imunit\u00e1rio<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"vc_row-680a7063b8792\" class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n<figure class=\"wpb_wrapper vc_figure\"><a class=\"vc_single_image-wrapper vc_box_border_grey prettyphoto\" href=\"https:\/\/veggie-style.com\/vegan-shop\/wp-content\/uploads\/2019\/09\/vroteina-vitamina-B12-post-A6.png\" target=\"_self\" data-rel=\"prettyPhoto[rel-26018-2699978538]\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img attachment-large\" src=\"https:\/\/veggie-style.com\/vegan-shop\/wp-content\/uploads\/2019\/09\/vroteina-vitamina-B12-post-A6.png\" sizes=\"(max-width: 687px) 100vw, 687px\" srcset=\"https:\/\/veggie-style.com\/vegan-shop\/wp-content\/uploads\/2019\/09\/vroteina-vitamina-B12-post-A6.png 687w, https:\/\/veggie-style.com\/vegan-shop\/wp-content\/uploads\/2019\/09\/vroteina-vitamina-B12-post-A6-300x223.png 300w, https:\/\/veggie-style.com\/vegan-shop\/wp-content\/uploads\/2019\/09\/vroteina-vitamina-B12-post-A6-600x446.png 600w\" alt=\"\" width=\"687\" height=\"511\" \/><\/a><\/figure>\n<\/div>\n<div class=\"wpb_single_image wpb_content_element vc_align_center\"><\/div>\n<div class=\"wpb_single_image wpb_content_element vc_align_center\"><\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<h6>A boa forma f\u00edsica \u00e9 o resultado de anos de treino dedicado e de uma dieta saud\u00e1vel - N\u00c3O \u00e9 o resultado da toma de um suplemento alimentar.<\/h6>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"vc_row-680a7063bbcbe\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1455193841743\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div id=\"fullwidth-block-680a7063bc3b2\" class=\"fullwidth-block clearfix\">\n<div class=\"fullwidth-block-inner\">\n<div class=\"container\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"title-h1\"><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">ESTILO VEGETARIANO FUNDADO EM 2011<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"styled-subtitle\"><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">Empresa vegana 100% fundada por Carlos Barbon - atleta de for\u00e7a vegan e ativista dos direitos dos animais<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"clearboth\"><\/div>\n<div class=\"gem-divider\"><\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-12\">\n<div class=\"vc_column-inner vc_custom_1455191337501\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n<figure class=\"wpb_wrapper vc_figure\">\n<div class=\"vc_single_image-wrapper vc_box_border_grey\"><\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-4 vc_col-lg-4 vc_hidden-md vc_hidden-sm vc_hidden-xs\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"clearboth\"><\/div>\n<div class=\"gem-divider\"><\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"title-h4\">100% VEGAN<\/div>\n<p><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">Empresa vegana 100% fundada por Carlos Barbon - atleta de for\u00e7a vegan e ativista dos direitos dos animais<\/span><\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"gem-divider\"><\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"title-h4\"><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">Sem alerg\u00e9nios<\/span><\/span><\/div>\n<p><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">Nas nossas pr\u00f3prias instala\u00e7\u00f5es de produ\u00e7\u00e3o em Alicante, garantimos que todo o equipamento nunca esteja em contacto com qualquer tipo de alerg\u00e9nio, como gl\u00faten, leite, ovos, frutos secos, etc.<\/span><\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"gem-divider\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"product-content entry-content\">\n<div id=\"vc_row-680207d90e565\" class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<h5 class=\"wpb_text_column wpb_content_element\">VITAMINA B12 VEGANA<\/h5>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"styled-subtitle\">\n<p>Complemento alimentar l\u00edquido pronto a tomar \u00e0 base de vitamina B12<br \/>\nSpray l\u00edquido<br \/>\n175 doses de 0,28 ml<br \/>\nQuantidade l\u00edquida: 50 ml<\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"featured_media":30492,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[184],"product_tag":[26,29,30,33],"class_list":{"0":"post-29708","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vitamina-d3-y-b12","7":"product_tag-acousto","8":"product_tag-clock","9":"product_tag-electronics","10":"product_tag-mega","12":"first","13":"instock","14":"featured","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/vroteina.com\/pt\/wp-json\/wp\/v2\/product\/29708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vroteina.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vroteina.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vroteina.com\/pt\/wp-json\/wp\/v2\/comments?post=29708"}],"version-history":[{"count":5,"href":"https:\/\/vroteina.com\/pt\/wp-json\/wp\/v2\/product\/29708\/revisions"}],"predecessor-version":[{"id":30650,"href":"https:\/\/vroteina.com\/pt\/wp-json\/wp\/v2\/product\/29708\/revisions\/30650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vroteina.com\/pt\/wp-json\/wp\/v2\/media\/30492"}],"wp:attachment":[{"href":"https:\/\/vroteina.com\/pt\/wp-json\/wp\/v2\/media?parent=29708"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vroteina.com\/pt\/wp-json\/wp\/v2\/product_brand?post=29708"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vroteina.com\/pt\/wp-json\/wp\/v2\/product_cat?post=29708"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vroteina.com\/pt\/wp-json\/wp\/v2\/product_tag?post=29708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}